{"id":864230,"date":"2025-03-03T16:06:00","date_gmt":"2025-03-03T14:06:00","guid":{"rendered":"https:\/\/tourism.com.de\/?p=864230"},"modified":"2025-03-03T16:06:04","modified_gmt":"2025-03-03T14:06:04","slug":"acores-10-raisons-pour-un-voyage-inoubliable","status":"publish","type":"post","link":"https:\/\/tourism.com.de\/fr\/acores-10-raisons-pour-un-voyage-inoubliable\/","title":{"rendered":"\ud83c\udfdd\ufe0f A\u00e7ores : 10 raisons pour un voyage inoubliable"},"content":{"rendered":"<p>J&rsquo;ai ouvert la carte, regard\u00e9 l'emplacement et j&rsquo;ai d\u00e9cid\u00e9 qu&rsquo;il \u00e9tait peu probable que je puisse me retrouver au milieu de l&rsquo;oc\u00e9an Atlantique dans les ann\u00e9es \u00e0 venir. Mais rien n&rsquo;est impossible! J&rsquo;ai rencontr\u00e9 2023 \u00e0 San Miguel, l&rsquo;\u00eele principale de l&rsquo;archipel des A\u00e7ores.\u00a0<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ce71e6f3.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ce71e6f3.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Pourquoi les A\u00e7ores sont-elles si attractives? L&rsquo;activit\u00e9 volcanique et l&rsquo;air humide de l&rsquo;Atlantique ont cr\u00e9\u00e9 un miracle: un coin de nature toujours verte avec un paysage montagneux, des lacs color\u00e9s, des c\u00f4tes rocheuses, des cascades et des geysers \u00e9mergeant des profondeurs de la terre.\u00a0<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/fr\/lima-guide-de-la-capitale-du-perou\/\" title=\"Le climat\">Le climat<\/a> ici est incroyable. En hiver, il fait environ +17 et en \u00e9t\u00e9, il fait environ +25. Mais le temps est si changeant qu&rsquo;un ciel clair et ensoleill\u00e9 peut \u00eatre recouvert de nuages \u200b\u200bde pluie en quelques minutes. Lorsque j&rsquo;ai pris l&rsquo;avion pour San Miguel, les pr\u00e9visions indiquaient des averses continues, ce qui est typique de la p\u00e9riode hivernale, mais en fait, je n&rsquo;ai jamais d\u00e9ball\u00e9 mon imperm\u00e9able &#8211; il a fait sec et chaud pendant sept jours. On dit que j&rsquo;ai beaucoup de chance.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-0.04076400-1718492230.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-0.04076400-1718492230.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p><a href=\"https:\/\/tourism.com.de\/fr\/pantheon-de-rome-histoire-photo-description-heures-douverture-prix-2021-faits-interessants-carte\/\" title=\"Passons\">Passons<\/a> aux attractions de l&rsquo;\u00eele de San Miguel. J&rsquo;ai h\u00e2te de vous parler des beaut\u00e9s qui valent la peine de s&rsquo;envoler pour les A\u00e7ores.<\/p>\n<h2><strong>Piscines naturelles thermales\u00a0<\/strong><\/h2>\n<p>A mon arriv\u00e9e, je me rends au village de Furnas. J&rsquo;ai d\u00e9cid\u00e9 que ce serait g\u00e9nial de nager dans des sources chaudes en pleine nature sauvage le 31 d\u00e9cembre, alors que les salades \u00e9taient hach\u00e9es dans les pays slaves.\u00a0<\/p>\n<p>La r\u00e9gion de Furnas est connue pour son activit\u00e9 volcanique, qui se poursuit encore aujourd&rsquo;hui. Un spectacle incroyable: \u00e0 certains endroits, des chaudrons d&rsquo;eau bouillante se forment dans le sol, ou de la vapeur avec une forte odeur sulfurique en sort tout simplement.<\/p>\n<p>\u00ab Pouvez-vous trouver des dumplings sur l&rsquo;\u00eele? Je sais o\u00f9 les cuisiner \u00bb, a plaisant\u00e9 mon mari. Les raviolis locaux ne sont pas fabriqu\u00e9s, mais ils utilisent des cuiseurs \u00e0 vapeur naturels et y font mijoter de la viande pour leur version du plat traditionnel <a href=\"https:\/\/tourism.com.de\/fr\/48-heures-a-porto-l-itineraire-parfait-pour-un-week-end\/\" title=\"de Porto\">de Porto<\/a> Gali \u00abCozido das Furnas \u00bb.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ce7b967f.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ce7b967f.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Dans le m\u00eame village se trouve le parc Terra Nostra (<strong>Parque Terra Nostra<\/strong>). Une visite co\u00fbte 10 euros. Imm\u00e9diatement \u00e0 l&rsquo;entr\u00e9e, vous verrez un lac de taille impressionnante avec de l&rsquo;eau rouge chaude (presque 40\u00b0C): sa couleur est due \u00e0 sa forte teneur en fer. Je vous pr\u00e9viens: les maillots de bain et les maillots de bain peuvent se tacher \u2013 portez-en des fonc\u00e9s ou ceux qui ne vous d\u00e9rangent pas.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-0.38732400-1718492247.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-0.38732400-1718492247.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Apr\u00e8s ou avant vos soins, promenez-vous dans le jardin botanique. Une r\u00e9serve de 12,5 hectares avec une vari\u00e9t\u00e9 de plantes et d&rsquo;arbres, des sentiers bien entretenus et des \u00e9tangs est un paradis.\u00a0<\/p>\n<p>\u00c0 distance de marche du parc Terra Nostra se trouve une autre piscine thermale &#8211; Po\u00e7a da Dona <strong>Beija<\/strong>. Entr\u00e9e &#8211; 8 euros pour 1h30. Croyez-moi, le corps n\u2019a pas besoin de plus: alors votre t\u00eate commence \u00e0 avoir des vertiges. Le complexe se compose de cinq petites piscines. Dans l\u2019un, vous pouvez vous allonger comme dans un bain, dans un autre, vous pouvez faire <a href=\"https:\/\/tourism.com.de\/fr\/25-meilleures-excursions-de-budva-au-montenegro-pas-cher-avec-un-guide\/\" title=\"un hydromassage\">un hydromassage<\/a> de vos \u00e9paules, dans le troisi\u00e8me, vous pouvez vous r\u00e9chauffer les os sur des pierres chaudes \u2013 c\u2019est g\u00e9nial! C&rsquo;est tr\u00e8s beau ici le soir quand les lumi\u00e8res s&rsquo;allument.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-0.78487600-1718492262.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-0.78487600-1718492262.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<h2><strong>Falaises volcaniques et phare de l&rsquo;Arnel<\/strong><\/h2>\n<p>Je suis tomb\u00e9 amoureux de cet endroit d\u00e8s la premi\u00e8re photo sur Internet. Il s&rsquo;est av\u00e9r\u00e9 que c&rsquo;\u00e9tait encore plus beau en personne. Vous pouvez apercevoir le phare de l&rsquo;Arnel (<strong>Farol do Arnel<\/strong>) depuis le site proche du village du Nordeste, mais je recommande d&rsquo;y descendre. \u00c0 propos, c&rsquo;est le premier phare des A\u00e7ores. Elle a \u00e9t\u00e9 construite au XIX\u00e8me si\u00e8cle.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ceb27a22.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ceb27a22.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Si vous descendez plus loin sur la route escarp\u00e9e, vous verrez une haute cascade. Ensuite, vous serez accueillis par des maisons de p\u00eacheurs, une jet\u00e9e avec des bateaux et enfin des roches de charbon. Ici, vous pouvez m\u00eame toucher et examiner de pr\u00e8s des couches de lave solidifi\u00e9e \u2013 c\u2019est terriblement beau! L&rsquo;oc\u00e9an sur fond de sable de cendres volcaniques semble particuli\u00e8rement azur. Ici, c&rsquo;est comme si vous \u00e9tiez en contact avec les quatre \u00e9l\u00e9ments: le feu, l&rsquo;eau, l&rsquo;air et la terre. Cet endroit me donne la chair de poule.\u00a0<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ceb84ccc.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ceb84ccc.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<h2><strong>Lacs multicolores dans crat\u00e8res volcaniques<\/strong><\/h2>\n<p><strong>Le lac h\u00e9t\u00e9rochronique du village de Sete<\/strong> Cidades est le plus grav\u00e9 dans ma m\u00e9moire: une partie a de l&rsquo;eau verte et l&rsquo;autre de l&rsquo;eau bleue. Il existe plusieurs plates-formes d&rsquo;observation dans les montagnes, d&rsquo;o\u00f9 vous pouvez voir le r\u00e9servoir sous diff\u00e9rents c\u00f4t\u00e9s. Je suis all\u00e9 au point de vue Miradouro do Cerrado das Freiras. Les hortensias fleurissent le long de la route au printemps, je pense que cela renforce l&rsquo;impression, mais m\u00eame en janvier, la vue ici m&rsquo;a fait monter les larmes aux yeux. Selon la l\u00e9gende, ces lacs \u00e9taient le lieu o\u00f9 <a href=\"https:\/\/tourism.com.de\/fr\/athenes-top-10-des-attractions-incontournables\/\" title=\"pleuraient\">pleuraient<\/a> les amoureux &#8211; une princesse aux yeux bleus et un berger aux yeux verts, parce que le roi leur avait interdit de se rencontrer.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cebe860a.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cebe860a.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Si vous vous rendez au m\u00eame point de vue, assurez-vous de vous arr\u00eater au Miradouro da <a href=\"https:\/\/tourism.com.de\/fr\/contrastes-de-goa-des-vacances-economiques-aux-vacances-de-luxe\/\" title=\"Lagoa\">Lagoa<\/a> <strong>de<\/strong> Santiago. De l\u00e0, vous verrez le lac Santiago. Il est entour\u00e9 de pentes verdoyantes des montagnes &#8211; un spectacle fascinant.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cec4fe8e.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cec4fe8e.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Dans la partie centrale de l&rsquo;\u00eele de S\u00e3o Miguel se trouve un autre lac form\u00e9 dans le crat\u00e8re d&rsquo;un volcan &#8211; <a href=\"https:\/\/tourism.com.de\/fr\/5-rituels-magiques-pour-des-vacances-parfaites-a-goa\/\" title=\"Lagoa\">Lagoa<\/a> do <strong>Fogo<\/strong>. Il est situ\u00e9 plus haut que les autres &#8211; \u00e0 environ 950 m\u00e8tres d&rsquo;altitude. Il faut admirer le r\u00e9servoir du point de vue tout en haut \u00e0 travers le brouillard. Mais si vous descendez un peu plus bas, il n&rsquo;y aura peut-\u00eatre pas de brume. Depuis les ponts d&rsquo;observation, vous pouvez voir non seulement la Lagoa de Fogo, mais aussi l&rsquo;oc\u00e9an, des deux c\u00f4t\u00e9s. Plaisir! Autour du \u00abLac de Feu \u00bb, comme son nom est traduit du portugais, il existe plusieurs <a href=\"https:\/\/tourism.com.de\/fr\/que-voir-a-varna-en-1-jour-itineraire-photo-description-carte\/\" title=\"itin\u00e9raires\">itin\u00e9raires<\/a> de randonn\u00e9e.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cec93526.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cec93526.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Pr\u00e8s du village dont je vous ai parl\u00e9 au tout d\u00e9but, il y a aussi un lac volcanique &#8211; Furnas (<strong>Lagoa das Furnas<\/strong>). Avec de l\u2019eau vert vif bouillonnant le long des rives.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ced07d45.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ced07d45.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<h2><strong>Les plus grandes <a href=\"https:\/\/tourism.com.de\/fr\/the-de-ceylan-un-voyage-a-travers-les-plantations-de-the\/\" title=\"plantations de th\u00e9\">plantations de th\u00e9<\/a> d&rsquo;Europe<\/strong><\/h2>\n<p>\u00c0 San Miguel se trouve la plus ancienne usine de th\u00e9 d&rsquo;Europe &#8211; Goreanna (<strong>F\u00e1brica de Ch\u00e1 Gorreana<\/strong>). Elle a \u00e9t\u00e9 fond\u00e9e dans la seconde moiti\u00e9 du XIXe si\u00e8cle. Le th\u00e9 ici est cueilli \u00e0 la main et fabriqu\u00e9 \u00e0 l\u2019aide d\u2019une technologie ancienne. Ensuite, ils sont emball\u00e9s \u00e0 la main dans des cartons.<\/p>\n<p>L&rsquo;atelier de production est ouvert \u00e0 tous. Au d\u00e9but, je pensais que c&rsquo;\u00e9tait <a href=\"https:\/\/tourism.com.de\/fr\/fonds-de-diamants-du-kremlin-de-moscou-histoire-photo-description-que-voir\/\" title=\"un mus\u00e9e\">un mus\u00e9e<\/a>, mais non, c&rsquo;est une v\u00e9ritable usine avec des \u00e9quipements anciens, o\u00f9 les feuilles sont encore s\u00e9ch\u00e9es. Apr\u00e8s <a href=\"https:\/\/tourism.com.de\/recomendet-getyourguide_com-product\">l&rsquo;excursion,<\/a> vous pourrez d\u00e9guster une tasse ou deux de th\u00e9 local tout en admirant les plantations, les pentes abruptes de l&rsquo;\u00eele et l&rsquo;oc\u00e9an sans fin. Le th\u00e9 est tr\u00e8s savoureux &#8211; j&rsquo;ai emport\u00e9 quelques paquets avec moi, je vous le recommande aussi.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ced66a4c.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0ced66a4c.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>A quelques minutes en voiture se trouve la deuxi\u00e8me usine de l&rsquo;\u00eele, Porto Formoso (<strong>F\u00e1brica de Ch\u00e1 de Porto Formoso<\/strong>). Elle propose \u00e9galement de d\u00e9guster son th\u00e9 sur la terrasse avec une vue imprenable. Il y a aussi un mus\u00e9e sur l&rsquo;histoire du th\u00e9 des A\u00e7ores \u00e0 l&rsquo;usine.<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cedaa758.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cedaa758.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<h2><strong>Plantations d&rsquo;ananas des A\u00e7ores\u00a0<\/strong><\/h2>\n<p>Il existe de nombreuses plantations de ce type sur l&rsquo;\u00eele, mais seules quelques-unes d&rsquo;entre elles sont ouvertes aux visiteurs. Je vous sugg\u00e8re de regarder celui qui se trouve presque en plein centre de la capitale des A\u00e7ores, Ponta Delgada &#8211; <strong>Planta\u00e7\u00e3o de Anan\u00e1s dos A\u00e7ores<\/strong>.<\/p>\n<p>Le climat local n\u2019est pas originaire de ces plantes, c\u2019est pourquoi les ananas m\u00fbrissent sous serre. Vous n&rsquo;avez pas besoin de payer pour les voir. De plus, \u00e0 la plantation, vous aurez \u00e9galement droit \u00e0 un verre de liqueur d&rsquo;ananas avec de la confiture. Tellement d\u00e9licieux! On dit que les ananas des A\u00e7ores sont faibles en sucre et riches en potassium, magn\u00e9sium, zinc, fer et brom\u00e9la\u00efne.\u00a0<\/p>\n<p><a href=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cee007e5.avif\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/tourism.com.de\/wp-content\/uploads\/2024\/07\/post-159855-661a0cee007e5.avif\" alt=\"A\u00e7ores - pourquoi vaut-il la peine de voler l\u00e0-bas?\"><\/a><\/p>\n<p>Ce n&rsquo;est qu&rsquo;une petite partie de la beaut\u00e9 des A\u00e7ores. J&rsquo;ai envie de revenir ici pour \u00abchasser\u00bb les baleines, visiter les plus belles plages, nager dans l&rsquo;oc\u00e9an \u00abchaud \u00bb, prendre <a href=\"https:\/\/tourism.com.de\/fr\/les-aeroports-les-plus-dangereux-du-monde-description-photo-ce-qui-est-remarquable\/\" title=\"des photos\">des photos<\/a> des plus belles <a href=\"https:\/\/tourism.com.de\/fr\/dalat-la-perle-des-montagnes-vietnamiennes\/\" title=\"cascades\">cascades<\/a>, parcourir des sentiers parsem\u00e9s d&rsquo;hortensias et voir d&rsquo;autres \u00eeles de l&rsquo;archipel. Oui, pendant mon voyage d\u2019une semaine, je n\u2019ai pas tout vu, mais c\u2019\u00e9tait largement suffisant pour tomber amoureux des A\u00e7ores \u00e0 feuilles persistantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le monde merveilleux des A\u00e7ores ! D\u00e9couvrez 10 raisons uniques de visiter ce paradis perdu de l&rsquo;oc\u00e9an Atlantique. Des paysages \u00e9poustouflants \u00e0 une culture unique, tout ce qui fait des A\u00e7ores une destination incontournable.<\/p>\n","protected":false},"author":1,"featured_media":805379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[551,1178,548],"tags":[],"class_list":["post-864230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spanien","category-allerlei","category-europa"],"_links":{"self":[{"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/posts\/864230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/comments?post=864230"}],"version-history":[{"count":0,"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/posts\/864230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/media\/805379"}],"wp:attachment":[{"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/media?parent=864230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/categories?post=864230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tourism.com.de\/fr\/wp-json\/wp\/v2\/tags?post=864230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}